{"id":2607,"date":"2022-12-05T20:08:06","date_gmt":"2022-12-05T17:08:06","guid":{"rendered":"https:\/\/dev.itmedia.md\/?page_id=2607"},"modified":"2024-09-18T13:49:02","modified_gmt":"2024-09-18T10:49:02","slug":"itmedia-agentia-de-publicitate-chisinau-moldova","status":"publish","type":"page","link":"https:\/\/dev.itmedia.md\/ro\/","title":{"rendered":"ITMEDIA, Agentia de Publicitate in Chisinau, Moldova"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2607\" class=\"elementor elementor-2607 elementor-2498\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d93fac6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d93fac6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b257caf\" data-id=\"b257caf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80e29dd elementor-widget elementor-widget-heading\" data-id=\"80e29dd\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Itmedia - agen\u021bie de publicitate in Chisinau, Moldova<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71175b3 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"71175b3\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d7507ba\" data-id=\"d7507ba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69416b9 elementor-widget elementor-widget-shortcode\" data-id=\"69416b9\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"8290\" class=\"elementor elementor-8290 elementor-8208\" data-elementor-settings=\"[]\">\n\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-074f4c7 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"074f4c7\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1dff37a\" data-id=\"1dff37a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4be62ea elementor-widget elementor-widget-html\" data-id=\"4be62ea\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"itm-nstm-pro\">\n<div class=\"itm-main-pro\">\n    <article id=\"itm_poster\">\n        <div id=\"itm_poster__header\">\n            <h2 id=\"itm_poster__header__title\" class=\"itm-header-1\" data-title=\"A venit timpul\">A venit timpul<\/h2>\n        <\/div>\n        \n        <div id=\"itm_poster__header_2\" class=\"itm_poster__header_2-ro\">\n            <h2 id=\"itm_poster__header__title\" class=\"itm-header-2 itm-header-2-ro\" data-title=\"PROMOVARII\"> PROMOVARII<\/h2>\n        <\/div>\n        \n <div id=\"itm_poster__button\">        \n<div style=\"text-align: center;\" class=\"itmnbutton\">\n    <a class=\"itmn1\" href=\"#popmake-2774\">\n      <span><\/span>\n      <span><\/span>\n      <span><\/span>\n      <span><\/span>\n      Primi\u021bi o consulta\u021bie\n    <\/a>\n<\/div>\n<\/div>\n        \n        <p id=\"itm_poster__anya\">Dezvoltarea site-urilor<\/p>\n        <p id=\"itm_poster__chris\">Promovarea afacerii<\/p>\n        <img decoding=\"async\" id=\"itm_poster__front_image\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/itmedia_manager.png\" alt=\"Furiosa Front image\">\n    <\/article>\n<\/div>\n<!-- partial -->\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66bc2ee elementor-section-stretched elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"66bc2ee\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4e83bd6\" data-id=\"4e83bd6\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ca23b6 mobile-center elementor-widget elementor-widget-heading\" data-id=\"9ca23b6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Publicitatea contextual\u0103 pe Google\/Yandex<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-563f0f0 elementor-widget elementor-widget-text-editor\" data-id=\"563f0f0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Garant\u0103m un flux continuu de clien\u021bi noi \u0219i solicit\u0103ri. Vom cre\u0219te traficul pe site. Posibilitatea de a vinde rapid produsul\/serviciul \u0219i monitorizarea complet\u0103 a cheltuielilor financiare nu sunt singurele avantaje ale publicit\u0103\u021bii contextuale.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d18e0d elementor-widget elementor-widget-html\" data-id=\"5d18e0d\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"text-align: center;\" class=\"itmnbutton\">\r\n    <a class=\"itmn1\" href=\"https:\/\/dev.itmedia.md\/ro\/publicitatea-contextuala-chisinau-moldova\/\">\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      Detalii\r\n    <\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d373ae1\" data-id=\"d373ae1\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7a5d4d elementor-widget elementor-widget-image\" data-id=\"d7a5d4d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_businessman_with_magnifying_glass_look_at_the_7be9e7c5-aba8-4b47-b7ef-c20beceb199b-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_businessman_with_magnifying_glass_look_at_the_7be9e7c5-aba8-4b47-b7ef-c20beceb199b.png 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_businessman_with_magnifying_glass_look_at_the_7be9e7c5-aba8-4b47-b7ef-c20beceb199b-300x300.png 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_businessman_with_magnifying_glass_look_at_the_7be9e7c5-aba8-4b47-b7ef-c20beceb199b-150x150.png 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_businessman_with_magnifying_glass_look_at_the_7be9e7c5-aba8-4b47-b7ef-c20beceb199b-768x768.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38295ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38295ad\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fab4fff\" data-id=\"fab4fff\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d24a582 mobile-left elementor-widget elementor-widget-heading\" data-id=\"d24a582\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Avantajele publicit\u0103\u021bii contextuale<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c1c68ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c1c68ca\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-02f95c5\" data-id=\"02f95c5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6dc8d3f elementor-widget elementor-widget-heading\" data-id=\"6dc8d3f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Anun\u021burile vor fi v\u0103zute<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2da426c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2da426c\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-adfd1d9 elementor-widget elementor-widget-text-editor\" data-id=\"adfd1d9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>doar de utilizatorii interesa\u021bi de produsele \u0219i serviciile dumneavoastr\u0103. Pute\u021bi alege regiunea \u0219i momentul \u00een care s\u0103 \u00eenc\u0103rca\u021bi publicitatea pentru a atrage publicul \u021bint\u0103.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42f974d elementor-widget elementor-widget-image\" data-id=\"42f974d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_big_crowd_without_paintings_view_from_afar_li_56e35af6-b7c0-4d1f-b8ce-900bd3298d6c-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_big_crowd_without_paintings_view_from_afar_li_56e35af6-b7c0-4d1f-b8ce-900bd3298d6c.png 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_big_crowd_without_paintings_view_from_afar_li_56e35af6-b7c0-4d1f-b8ce-900bd3298d6c-300x300.png 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_big_crowd_without_paintings_view_from_afar_li_56e35af6-b7c0-4d1f-b8ce-900bd3298d6c-150x150.png 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_big_crowd_without_paintings_view_from_afar_li_56e35af6-b7c0-4d1f-b8ce-900bd3298d6c-768x768.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f1eed8e\" data-id=\"f1eed8e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ee91c1 elementor-widget elementor-widget-heading\" data-id=\"3ee91c1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">List\u0103 nelimitat\u0103<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5eda8f0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5eda8f0\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bed3c99 elementor-widget elementor-widget-text-editor\" data-id=\"bed3c99\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">pute\u021bi folosi o list\u0103 nelimitat\u0103 de cuvinte-cheie pentru a promovarea serviciilor\/produselor dumneavoastr\u0103.\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0\u00a0<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dccbf9e elementor-widget elementor-widget-image\" data-id=\"dccbf9e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_infinity_on_painting_light_gray_background_digital_art_3a6d99d9-064e-49c0-bdb1-f8bc0b68705f-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_infinity_on_painting_light_gray_background_digital_art_3a6d99d9-064e-49c0-bdb1-f8bc0b68705f.png 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_infinity_on_painting_light_gray_background_digital_art_3a6d99d9-064e-49c0-bdb1-f8bc0b68705f-300x300.png 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_infinity_on_painting_light_gray_background_digital_art_3a6d99d9-064e-49c0-bdb1-f8bc0b68705f-150x150.png 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_infinity_on_painting_light_gray_background_digital_art_3a6d99d9-064e-49c0-bdb1-f8bc0b68705f-768x768.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d164873 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d164873\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e4d2a18\" data-id=\"e4d2a18\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2ddb58 elementor-widget elementor-widget-heading\" data-id=\"e2ddb58\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Rezultate rapide<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee9e765 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ee9e765\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62bbb15 elementor-widget elementor-widget-text-editor\" data-id=\"62bbb15\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Rezultate \u0219i profit apar cur\u00e2nd, f\u0103r\u0103 a fi nevoie de a\u0219teptarea de luni de zile. Clien\u021bi noi vor veni chiar de m\u00e2ine!<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2953725 elementor-widget elementor-widget-image\" data-id=\"2953725\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_fast_realitic_businessman_on_painting_light_gray_backgr_d4b923da-233b-4118-b910-e0dc4fe3351b-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_fast_realitic_businessman_on_painting_light_gray_backgr_d4b923da-233b-4118-b910-e0dc4fe3351b.png 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_fast_realitic_businessman_on_painting_light_gray_backgr_d4b923da-233b-4118-b910-e0dc4fe3351b-300x300.png 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_fast_realitic_businessman_on_painting_light_gray_backgr_d4b923da-233b-4118-b910-e0dc4fe3351b-150x150.png 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_fast_realitic_businessman_on_painting_light_gray_backgr_d4b923da-233b-4118-b910-e0dc4fe3351b-768x768.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2fe1634\" data-id=\"2fe1634\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce4fe62 elementor-widget elementor-widget-heading\" data-id=\"ce4fe62\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Cadou<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8d123a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f8d123a\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-593395b elementor-position-left elementor-vertical-align-middle zvezdi-kak-mi elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"593395b\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-gift\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tV\u0103 analiz\u0103m concuren\u021bii pe post de cadou!\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34e1943 elementor-widget elementor-widget-image\" data-id=\"34e1943\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_businessman_with_magnifying_glass_look_at_crowd_on_pain_dfad6f25-0f4a-4c22-ad6c-201457e2bf5f-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_businessman_with_magnifying_glass_look_at_crowd_on_pain_dfad6f25-0f4a-4c22-ad6c-201457e2bf5f.png 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_businessman_with_magnifying_glass_look_at_crowd_on_pain_dfad6f25-0f4a-4c22-ad6c-201457e2bf5f-300x300.png 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_businessman_with_magnifying_glass_look_at_crowd_on_pain_dfad6f25-0f4a-4c22-ad6c-201457e2bf5f-150x150.png 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_businessman_with_magnifying_glass_look_at_crowd_on_pain_dfad6f25-0f4a-4c22-ad6c-201457e2bf5f-768x768.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b220a23 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b220a23\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bc56842\" data-id=\"bc56842\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-137050f elementor-widget elementor-widget-html\" data-id=\"137050f\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"text-align: center;\" class=\"itmnbutton\">\r\n    <a class=\"itmn1\" href=\"https:\/\/dev.itmedia.md\/ro\/publicitatea-contextuala-chisinau-moldova\/\">\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      Detalii\r\n    <\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a757094 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a757094\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ab4358\" data-id=\"4ab4358\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48d0134 mobile-left elementor-widget elementor-widget-heading\" data-id=\"48d0134\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Studiu de caz<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b783cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1b783cc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a563cad\" data-id=\"a563cad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01b8297 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"01b8297\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"481\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/kt91vbhyp4-1.webp\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/kt91vbhyp4-1.webp 724w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/kt91vbhyp4-1-300x225.webp 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0392434 elementor-invisible\" data-id=\"0392434\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-447e988 elementor-widget elementor-widget-heading\" data-id=\"447e988\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\nCre\u0219terea cu 315% a v\u00e2nz\u0103rilor biletelor\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e584e34 elementor-widget elementor-widget-text-editor\" data-id=\"e584e34\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00a0<\/p>\n<p>Transport pentru pasageri pe diferite rute<\/p>\n<p>transportpersoane.md<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f68e9ca elementor-widget elementor-widget-html\" data-id=\"f68e9ca\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"itmnbutton\">\r\n    <a class=\"itmn\" href=\"#popmake-2774\">\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      Vreau la fel\r\n    <\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ad1ae2 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ad1ae2\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c280054\" data-id=\"c280054\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-864b3e6 elementor-widget elementor-widget-image\" data-id=\"864b3e6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_man_designer_sit_on_the_table_on_table_is_mac_672032d4-3017-433d-be5f-2ec57712a590-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_man_designer_sit_on_the_table_on_table_is_mac_672032d4-3017-433d-be5f-2ec57712a590.png 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_man_designer_sit_on_the_table_on_table_is_mac_672032d4-3017-433d-be5f-2ec57712a590-300x300.png 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_man_designer_sit_on_the_table_on_table_is_mac_672032d4-3017-433d-be5f-2ec57712a590-150x150.png 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_man_designer_sit_on_the_table_on_table_is_mac_672032d4-3017-433d-be5f-2ec57712a590-768x768.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-881649f\" data-id=\"881649f\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94997f5 mobile-center elementor-widget elementor-widget-heading\" data-id=\"94997f5\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Promovarea SMM<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f48a7bd elementor-widget elementor-widget-text-editor\" data-id=\"f48a7bd\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Capacitatea de a forma afinit\u0103\u021bi cu fiecare persoan\u0103 constituie un set de competen\u021be distincte. \u00cen plus, domeniul nostru central de expertiz\u0103 se concentreaz\u0103 pe valorificarea la maximum a acestui set de competen\u021be. Abordarea noastr\u0103 implic\u0103 nu doar atragerea unui nou grup demografic, ci \u0219i cultivarea interesului acestora \u0219i ghidarea lor c\u0103tre o conversa\u021bie de succes.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-add3ddd elementor-widget elementor-widget-html\" data-id=\"add3ddd\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"text-align: center;\" class=\"itmnbutton\">\r\n    <a class=\"itmn1\" href=\"https:\/\/dev.itmedia.md\/ro\/agentia-itmedia-smm-promovare-in-chisinau-moldova\/\">\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      Detalii\r\n    <\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b607232 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b607232\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9842284\" data-id=\"9842284\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-816bcf5 mobile-left elementor-widget elementor-widget-heading\" data-id=\"816bcf5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Avantajele promov\u0103rii SMM<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e4763a5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e4763a5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-755c9f4\" data-id=\"755c9f4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1e4249 elementor-widget elementor-widget-heading\" data-id=\"d1e4249\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Acoperire extins\u0103<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8cc88f5 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8cc88f5\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abdea68 elementor-widget elementor-widget-text-editor\" data-id=\"abdea68\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00cen prezent, audien\u021ba platformelor de social media o dep\u0103\u0219e\u0219te pe cea a televiziunii.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-97d9034\" data-id=\"97d9034\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62a13c2 elementor-widget elementor-widget-heading\" data-id=\"62a13c2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Concepte creative<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ed2a69 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0ed2a69\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-075c0d5 elementor-widget elementor-widget-text-editor\" data-id=\"075c0d5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Gener\u0103m idei creative pentru promovarea brandului pe social media \u0219i alegem metode unice de livrare a con\u021binutului c\u0103tre publicul \u021bint\u0103.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f86865 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f86865\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1547b46\" data-id=\"1547b46\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-059dfab elementor-widget elementor-widget-heading\" data-id=\"059dfab\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Loialitatea clien\u021bilor<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9effb9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d9effb9\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1fe0c1 elementor-widget elementor-widget-text-editor\" data-id=\"d1fe0c1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Promovarea SMM are un caracter discret \u0219i este perceput de utilizatori nu ca publicitate, ci ca un bloc de \u0219tiri.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a7a4815\" data-id=\"a7a4815\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d130031 elementor-widget elementor-widget-heading\" data-id=\"d130031\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Rezultate<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-038e43a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"038e43a\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb7bff3 elementor-widget elementor-widget-text-editor\" data-id=\"eb7bff3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Succesul campaniilor noastre publicitarea este de minimum 200%. Bugetul dumneavoastr\u0103 este pe m\u00e2ini sigure.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34ba357 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34ba357\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73780d2\" data-id=\"73780d2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c80c777 elementor-widget elementor-widget-html\" data-id=\"c80c777\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"text-align: center;\" class=\"itmnbutton\">\r\n    <a class=\"itmn1\" href=\"https:\/\/dev.itmedia.md\/ro\/agentia-itmedia-smm-promovare-in-chisinau-moldova\/\">\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      Detalii\r\n    <\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10be48a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10be48a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-379b64d\" data-id=\"379b64d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-acc7a91 mobile-left elementor-widget elementor-widget-heading\" data-id=\"acc7a91\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Caz despre promovarea SMM<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dfdd51f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dfdd51f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-922e9c3\" data-id=\"922e9c3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d6e69f3 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"d6e69f3\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/bad-in-love-632816_1024x1024@2x-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/bad-in-love-632816_1024x1024@2x-1024x1024.jpg 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/bad-in-love-632816_1024x1024@2x-300x300.jpg 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/bad-in-love-632816_1024x1024@2x-150x150.jpg 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/bad-in-love-632816_1024x1024@2x-768x768.jpg 768w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/bad-in-love-632816_1024x1024@2x.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bcf985f elementor-invisible\" data-id=\"bcf985f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c63f66 elementor-widget elementor-widget-heading\" data-id=\"5c63f66\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cre\u0219terea v\u00e2nz\u0103rilor de la 5 000 de euro pe lun\u0103 la 42 000 de euro, \u00een doar jum\u0103tate de an.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-245c318 elementor-widget elementor-widget-text-editor\" data-id=\"245c318\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>\u00a0<\/p>\n<p>Case 99paintings.de | Magazin online de tablouri din Germania<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0807eae elementor-widget elementor-widget-html\" data-id=\"0807eae\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"itmnbutton\">\r\n    <a class=\"itmn\" href=\"#popmake-2774\">\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n       Vreau la fel\r\n    <\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b88c153 elementor-section-stretched elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b88c153\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-331c033\" data-id=\"331c033\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-799effe mobile-center elementor-widget elementor-widget-heading\" data-id=\"799effe\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/p\">Promovarea SEO<\/a><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ff158c elementor-widget elementor-widget-text-editor\" data-id=\"2ff158c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Promovarea rapid\u0103 a site-ului , avansarea pozi\u021biilor \u00een top \u00eencepe \u00een dou\u0103 s\u0103pt\u0103m\u00e2ni!<\/p>\n<p>Atragerea publicului \u021bint\u0103 este sarcina noastr\u0103 principal\u0103.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-532f290 elementor-widget elementor-widget-html\" data-id=\"532f290\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"text-align: center;\" class=\"itmnbutton\">\r\n    <a class=\"itmn1\" href=\"https:\/\/dev.itmedia.md\/ro\/seo-promovare-chisinau-moldova\/\">\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      Detalii\r\n    <\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8e66373\" data-id=\"8e66373\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f91af7c elementor-widget elementor-widget-image\" data-id=\"f91af7c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_man_from_behind_in_a_business_suit_with_magni_006cc403-88a0-4ed3-9f96-2cce286614e6-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_man_from_behind_in_a_business_suit_with_magni_006cc403-88a0-4ed3-9f96-2cce286614e6.png 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_man_from_behind_in_a_business_suit_with_magni_006cc403-88a0-4ed3-9f96-2cce286614e6-300x300.png 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_man_from_behind_in_a_business_suit_with_magni_006cc403-88a0-4ed3-9f96-2cce286614e6-150x150.png 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_man_from_behind_in_a_business_suit_with_magni_006cc403-88a0-4ed3-9f96-2cce286614e6-768x768.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13843cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13843cf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aa8cbc2\" data-id=\"aa8cbc2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c214acf mobile-left elementor-widget elementor-widget-heading\" data-id=\"c214acf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Avantajele promov\u0103rii SEO<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6487c53 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6487c53\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c2cbb73\" data-id=\"c2cbb73\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1471aa elementor-widget elementor-widget-heading\" data-id=\"f1471aa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Lipsa bugetului publicitar<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c20145 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1c20145\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4ba703 elementor-widget elementor-widget-text-editor\" data-id=\"f4ba703\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Spre deosebire de alte canale de promovare, promovarea SEO \u00een Moldova nu necesit\u0103 un buget publicitar, pre\u021bul serviciului fiind singura investi\u021bie.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d5037b elementor-widget elementor-widget-image\" data-id=\"3d5037b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_two_businessmen_shaking_hands_light_gray_background_dig_5014d48f-202c-433f-821f-7f8467698de0-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_two_businessmen_shaking_hands_light_gray_background_dig_5014d48f-202c-433f-821f-7f8467698de0.png 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_two_businessmen_shaking_hands_light_gray_background_dig_5014d48f-202c-433f-821f-7f8467698de0-300x300.png 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_two_businessmen_shaking_hands_light_gray_background_dig_5014d48f-202c-433f-821f-7f8467698de0-150x150.png 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_two_businessmen_shaking_hands_light_gray_background_dig_5014d48f-202c-433f-821f-7f8467698de0-768x768.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5b69f16\" data-id=\"5b69f16\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07352b5 elementor-widget elementor-widget-heading\" data-id=\"07352b5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Un rezultat pe termen lung\n<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96e0cb9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"96e0cb9\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d7ab1f elementor-widget elementor-widget-text-editor\" data-id=\"6d7ab1f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">\u00cen alte tipuri de promovare, dac\u0103 vi se termina bugetul, anun\u021burile dumneavoastr\u0103 dispar. \u00cen promovarea SEO, rezultatul e suficient pentru cel pu\u021bin doi ani.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6074609 elementor-widget elementor-widget-image\" data-id=\"6074609\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_businessman_analyzes_web-site_light_gray_back_d8069391-7602-44e6-ba14-eded01bba55b-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_businessman_analyzes_web-site_light_gray_back_d8069391-7602-44e6-ba14-eded01bba55b.png 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_businessman_analyzes_web-site_light_gray_back_d8069391-7602-44e6-ba14-eded01bba55b-300x300.png 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_businessman_analyzes_web-site_light_gray_back_d8069391-7602-44e6-ba14-eded01bba55b-150x150.png 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_businessman_analyzes_web-site_light_gray_back_d8069391-7602-44e6-ba14-eded01bba55b-768x768.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58df8ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58df8ef\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fef291d\" data-id=\"fef291d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0503674 elementor-widget elementor-widget-heading\" data-id=\"0503674\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00cencredere <\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6f4da1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f6f4da1\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47e9436 elementor-widget elementor-widget-text-editor\" data-id=\"47e9436\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">\u00cencrederea \u00een rezultatele c\u0103ut\u0103rii organice (SEO) e mai mare, deseori utilizatorii special omit anun\u021burile \u0219i trec la rezultatele c\u0103ut\u0103rii organice<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bfa36e elementor-widget elementor-widget-image\" data-id=\"6bfa36e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_person_businessman_make_money_light_gray_back_8e7f6ac0-b7f8-4403-8cbd-7680512b2485-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_person_businessman_make_money_light_gray_back_8e7f6ac0-b7f8-4403-8cbd-7680512b2485.png 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_person_businessman_make_money_light_gray_back_8e7f6ac0-b7f8-4403-8cbd-7680512b2485-300x300.png 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_person_businessman_make_money_light_gray_back_8e7f6ac0-b7f8-4403-8cbd-7680512b2485-150x150.png 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_person_businessman_make_money_light_gray_back_8e7f6ac0-b7f8-4403-8cbd-7680512b2485-768x768.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9013c44\" data-id=\"9013c44\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae81aaf elementor-widget elementor-widget-heading\" data-id=\"ae81aaf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Cel mai avantajos canal de promovare<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e18eb3b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e18eb3b\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5df9902 elementor-widget elementor-widget-text-editor\" data-id=\"5df9902\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Lipsa bugetului \u0219i un rezultat suficient pentru cel pu\u021bin 2 ani localizeaz\u0103 promovarea SEO \u00een fruntea canalelor de promovare dup\u0103 randament.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-613535d elementor-widget elementor-widget-image\" data-id=\"613535d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_businessman_with_golden_cup_light_gray_backgr_4fde774d-cdd9-4b00-b3d2-f3da016c28ab-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_businessman_with_golden_cup_light_gray_backgr_4fde774d-cdd9-4b00-b3d2-f3da016c28ab.png 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_businessman_with_golden_cup_light_gray_backgr_4fde774d-cdd9-4b00-b3d2-f3da016c28ab-300x300.png 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_businessman_with_golden_cup_light_gray_backgr_4fde774d-cdd9-4b00-b3d2-f3da016c28ab-150x150.png 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_businessman_with_golden_cup_light_gray_backgr_4fde774d-cdd9-4b00-b3d2-f3da016c28ab-768x768.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-da65cec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da65cec\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1efe7d3\" data-id=\"1efe7d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0296f9 elementor-widget elementor-widget-html\" data-id=\"b0296f9\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"text-align: center;\" class=\"itmnbutton\">\r\n    <a class=\"itmn1\" href=\"https:\/\/dev.itmedia.md\/ro\/agentia-itmedia-smm-promovare-in-chisinau-moldova\/\">\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      Detalii\r\n    <\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b6ba54 elementor-section-stretched elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6b6ba54\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-358c715\" data-id=\"358c715\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b15b62 mobile-center elementor-widget elementor-widget-heading\" data-id=\"4b15b62\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DEZVOLTAREA DE LANDING PAGE (A PAGINII DE ATERIZARE)<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4f5cb3 elementor-widget elementor-widget-text-editor\" data-id=\"e4f5cb3\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Cre\u0103m Landing page-urile la comand\u0103. Dumneavoastr\u0103 dori\u021bi s\u0103 primi\u021bi rezultatul maxim? Fiecare proiect este supus unui audit de c\u0103tre marketologul nostru, introducem corective, \u00eembun\u0103t\u0103\u021bim calit\u0103\u021bile de v\u00e2nzare, ve\u021bi primi landing page care va asigura v\u00e2nz\u0103rile!<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26467c9 elementor-widget elementor-widget-html\" data-id=\"26467c9\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"text-align: center;\" class=\"itmnbutton\">\r\n    <a class=\"itmn1\" href=\"#popmake-2774\">\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      Primi\u021bi o consulta\u021bie\r\n    <\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e986092\" data-id=\"e986092\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-948f961 elementor-widget elementor-widget-image\" data-id=\"948f961\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_small_hight_tech_house_on_painting_white_light_gray_bac_6b6fb8f9-61ac-4475-9ec6-6743ed1a9914-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_small_hight_tech_house_on_painting_white_light_gray_bac_6b6fb8f9-61ac-4475-9ec6-6743ed1a9914.png 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_small_hight_tech_house_on_painting_white_light_gray_bac_6b6fb8f9-61ac-4475-9ec6-6743ed1a9914-300x300.png 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_small_hight_tech_house_on_painting_white_light_gray_bac_6b6fb8f9-61ac-4475-9ec6-6743ed1a9914-150x150.png 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_small_hight_tech_house_on_painting_white_light_gray_bac_6b6fb8f9-61ac-4475-9ec6-6743ed1a9914-768x768.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8340e16 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8340e16\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3e67fd8\" data-id=\"3e67fd8\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0239957 mobile-center elementor-widget elementor-widget-heading\" data-id=\"0239957\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dezvoltarea site-urilor de orice dificultate <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af34d72 elementor-widget elementor-widget-text-editor\" data-id=\"af34d72\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Folosim tehnologii performante \u00een dezvoltarea site-urilor. Lucr\u0103m cu framework-uri, CMS populare precum WordPress, Joomla, Tilda. Dezvolt\u0103m site-uri scrise de la zero la comand\u0103 \u00een Moldova, Rusia, Europa \u0219i America.<\/span><\/p><p><span style=\"font-weight: 400;\">\u00cen acordul despre dezvoltarea site-ului sunt clar indica\u021bi termenii, \u0219i noi \u00eentotdeauna le respect\u0103m!\u00a0<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64080c3 elementor-widget elementor-widget-html\" data-id=\"64080c3\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"text-align: center;\" class=\"itmnbutton\">\r\n    <a class=\"itmn1\" href=\"https:\/\/dev.itmedia.md\/ro\/creare-site-moldova\/\">\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      Detalii\r\n    <\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-83fba28\" data-id=\"83fba28\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2fe689a elementor-widget elementor-widget-image\" data-id=\"2fe689a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_shopping_corporation_white_light_gray_background_digita_534a8526-63fe-4d99-9cfc-80a788453751-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_shopping_corporation_white_light_gray_background_digita_534a8526-63fe-4d99-9cfc-80a788453751.png 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_shopping_corporation_white_light_gray_background_digita_534a8526-63fe-4d99-9cfc-80a788453751-300x300.png 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_shopping_corporation_white_light_gray_background_digita_534a8526-63fe-4d99-9cfc-80a788453751-150x150.png 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_shopping_corporation_white_light_gray_background_digita_534a8526-63fe-4d99-9cfc-80a788453751-768x768.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5461f8a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5461f8a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7f5800f\" data-id=\"7f5800f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3083843 elementor-widget elementor-widget-heading\" data-id=\"3083843\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Clien\u021bii no\u0219tri<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a999988 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a999988\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5fe43f7\" data-id=\"5fe43f7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a4d857 elementor-widget elementor-widget-shortcode\" data-id=\"8a4d857\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"smls-main-logo-outer-836018760 smls-main-logo-wrapper\">\r\n      <div class=\"smls-grid-container-template-2 smls-grid smls-grid-column-4 smls-tablet-column-2 smls-mobile-column-2  smls-hover-type-1 clearfix\r\n     \">\r\n            <div class=\"smls-grid-image-wrap  main-div-1\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/main-logo.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-1\" id=\"contact-div-1\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-2\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/0-02-05-288b00f62c6851e6953f09213fca0cd317a68ea34c43abdfc10e3763ddfcc5a5_88c262e3d51fc679.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-2\" id=\"contact-div-2\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-3\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/alex.jpg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-3\" id=\"contact-div-3\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-4\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/termostar.jpg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-4\" id=\"contact-div-4\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-5\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/Untitled-3-150x150-1.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-5\" id=\"contact-div-5\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-6\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2021\/09\/logo-viniatraian-retina.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-6\" id=\"contact-div-6\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-7\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2021\/09\/Logo-5.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-7\" id=\"contact-div-7\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-8\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/99-logo-BLACK-text-only_180x.webp\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-8\" id=\"contact-div-8\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-9\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/logo-2.svg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-9\" id=\"contact-div-9\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-10\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/logo.jpg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-10\" id=\"contact-div-10\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-11\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/cropped-new-main-logo.018d4590.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-11\" id=\"contact-div-11\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-12\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/romobil.md-logo.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-12\" id=\"contact-div-12\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-13\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/dentlist.jpg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-13\" id=\"contact-div-13\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-14\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/seven.jpg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-14\" id=\"contact-div-14\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-15\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/asmorind.jpg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-15\" id=\"contact-div-15\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-16\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/seven3.jpg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-16\" id=\"contact-div-16\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-17\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2021\/10\/myskin-logo.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-17\" id=\"contact-div-17\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-18\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/logo-4.svg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-18\" id=\"contact-div-18\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-19\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2021\/09\/logo01.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-19\" id=\"contact-div-19\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-20\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/cropped-0-02-05-6b530042474f0f26d9f37d921f2917847412fda32502d3dc17dc3dbe87d637db_5a066005c3752830.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-20\" id=\"contact-div-20\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-21\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/ednateric-trans.svg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-21\" id=\"contact-div-21\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-22\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/calator-md.svg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-22\" id=\"contact-div-22\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-23\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/transerictur.svg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-23\" id=\"contact-div-23\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-24\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2021\/10\/logo-6.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-24\" id=\"contact-div-24\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-25\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/logo_perfectum-module.md_.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-25\" id=\"contact-div-25\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-26\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/lalalaser-logo-1.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-26\" id=\"contact-div-26\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-27\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/laser-epil-studio.jpg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-27\" id=\"contact-div-27\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-28\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/holyland-logo-1.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-28\" id=\"contact-div-28\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n          <\/div>\r\n          <style type=\"text\/css\">\r\n            .popup-contact .smls-overlay-contact-info {\r\n              display: none;\r\n            }\r\n            .popup-contact .smls-overlay-contact-info.active {\r\n              display: block;\r\n              position: fixed;\r\n              width: 30%;\r\n              height: 37%;\r\n              background: #000000a6;\r\n              color: #fff;\r\n              left: 30%;\r\n              right: 0;\r\n              top: 30%;\r\n              z-index: 999;\r\n              text-align: center;\r\n            }\r\n            .popup-contact .smls-overlay-contact-info.active .smls-popup-open {\r\n              display: none;\r\n            }\r\n            .popup-contact .smls-overlay-contact-info.active .popup-content {\r\n              visibility: visible;\r\n              \r\n            }\r\n            .popup-content h4, .popup-content h5 {\r\n              color: #FFF;\r\n            }\r\n\r\n\r\n          <\/style>\r\n            <\/div>\r\n  <style>\n    .smls-main-logo-outer-836018760.smls-main-logo-wrapper {\n        width: 100%;\n        margin:0 auto;\n    }\n    .smls-main-logo-outer-836018760 .smls-grid-container-template-1 .smls-grid-each-item:before,\n    .smls-main-logo-outer-836018760 .smls-grid-container-template-1 .smls-grid-image-wrap:before,\n    .smls-main-logo-outer-836018760 .smls-grid-container-template-2 .smls-grid-each-item:before,\n    .smls-main-logo-outer-836018760 .smls-grid-container-template-2 .smls-grid-image-wrap:before {\n\n        border-left: 1px solid #e9e9e9;\n    }\n    .smls-main-logo-outer-836018760 .smls-grid-container-template-1 .smls-grid-each-item:after,\n    .smls-main-logo-outer-836018760 .smls-grid-container-template-1 .smls-grid-image-wrap:after,\n    .smls-main-logo-outer-836018760 .smls-grid-container-template-2 .smls-grid-each-item:after,\n    .smls-main-logo-outer-836018760 .smls-grid-container-template-2 .smls-grid-image-wrap:after {\n        border-bottom: 1px solid #e9e9e9;\n    }\n    .smls-main-logo-outer-836018760 .smls-grid-container-template-2 {\n        border: 1px solid #e9e9e9;\n    }\n\n    .smls-main-logo-outer-836018760 .smls-carousel-pager-template-2.owl-theme .owl-dots .owl-dot span:before\n    {\n        background-color:  #0d98dc;\n\n    }\n    .smls-main-logo-outer-836018760 .smls-carousel-pager-template-2.owl-theme .owl-dots .owl-dot span {\n        background:  #7c7c7c;\n    }\n\n    .smls-main-logo-outer-836018760 .smls-carousel-arrow-type-1.owl-theme .owl-controls .owl-nav [class*=owl-]:hover {\n        background-color: rgba(71, 71, 71, 0.7);\n    }\n    .smls-main-logo-outer-836018760 .smls-carousel-arrow-type-1.owl-theme .owl-controls .owl-nav [class*=owl-] {\n        background-color: #474747;\n    }\n    .smls-main-logo-outer-836018760 .smls-carousel-arrow-type-2.owl-theme .owl-controls .owl-nav [class*=owl-] {\n        background-color:  #474747;\n    }\n    .smls-main-logo-outer-836018760 .smls-carousel-arrow-type-2.owl-theme .owl-controls .owl-nav [class*=owl-]:hover {\n        background-color: rgba(71, 71, 71, 0.7);\n    }\n    .smls-main-logo-outer-836018760 .smls-carousel-arrow-type-3.owl-theme .owl-controls .owl-nav [class*=owl-] {\n        border: 2px solid #474747;\n\n    }\n    .smls-main-logo-outer-836018760 .smls-carousel-arrow-type-3.owl-theme .owl-controls .owl-nav [class*=owl-]:before {\n        background-color: rgba(71, 71, 71, 0.7);\n    }\n    .smls-main-logo-outer-836018760 .smls-carousel-arrow-type-3.owl-theme .owl-controls .owl-nav [class*=owl-]:hover {\n        border-color: rgba(71, 71, 71, 0.7);\n    }\n    .smls-main-logo-outer-836018760 .smls-carousel-arrow-type-4.owl-theme .owl-controls .owl-nav [class*=owl-] {\n        border: 2px solid #474747;\n        color: #474747;\n    }\n    .smls-main-logo-outer-836018760 .smls-carousel-arrow-type-4.owl-carousel .owl-controls .owl-nav [class*=owl-]:hover {\n        background-color: rgba(71, 71, 71, 0.7);\n        color: #333333;\n    }\n    .smls-main-logo-outer-836018760 .smls-carousel-arrow-type-5.owl-theme .owl-controls .owl-nav [class*=owl-] {\n        background-color:  #474747;\n\n    }\n\n    .smls-main-logo-outer-836018760 .smls-carousel-template-2.owl-carousel .smls-carousel-four-items {\n        border: 1px solid  #eee;\n    }\n\n<\/style><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10e7b05 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10e7b05\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-394e34a\" data-id=\"394e34a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea944b8 elementor-widget elementor-widget-heading\" data-id=\"ea944b8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\u0219i mul\u021bi al\u021bi<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4787ac3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4787ac3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8309c2e\" data-id=\"8309c2e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77ce188 elementor-widget elementor-widget-html\" data-id=\"77ce188\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"text-align: center;\" class=\"itmnbutton\">\r\n    <a class=\"itmn1\" href=\"#popmake-2774\">\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      Formulati o cerere\r\n    <\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-254dede5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"254dede5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4539f3bd\" data-id=\"4539f3bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-126b229 elementor-widget elementor-widget-heading\" data-id=\"126b229\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ultimele \u0219tiri<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10ac0826 elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-posts--show-avatar elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"10ac0826\" data-element_type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-8611 post type-post status-publish format-standard has-post-thumbnail hentry category-categoria-generala\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/dev.itmedia.md\/ro\/matricea-de-produse-arma-secreta-pentru-cresterea-vanzarilor-si-dezvoltarea-afacerii\/\" target=\"_blank\">\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/10\/itmedia-produktovaya-matricza-sekretnoe-oruzhie-dlya-uvelicheniya-prodazh-i-rosta-biznesa.webp\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/10\/itmedia-produktovaya-matricza-sekretnoe-oruzhie-dlya-uvelicheniya-prodazh-i-rosta-biznesa.webp 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/10\/itmedia-produktovaya-matricza-sekretnoe-oruzhie-dlya-uvelicheniya-prodazh-i-rosta-biznesa-300x300.webp 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/10\/itmedia-produktovaya-matricza-sekretnoe-oruzhie-dlya-uvelicheniya-prodazh-i-rosta-biznesa-150x150.webp 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/10\/itmedia-produktovaya-matricza-sekretnoe-oruzhie-dlya-uvelicheniya-prodazh-i-rosta-biznesa-768x768.webp 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Categoria general\u0103<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img alt='\u0410\u0440\u0442\u0443\u0440' src='https:\/\/secure.gravatar.com\/avatar\/39aac8628cc4f633ab4887737e18f8cde23187b7958281a447f7e27d0524ef7b?s=128&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/39aac8628cc4f633ab4887737e18f8cde23187b7958281a447f7e27d0524ef7b?s=256&#038;d=mm&#038;r=g 2x' class='avatar avatar-128 photo' height='128' width='128' \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/dev.itmedia.md\/ro\/matricea-de-produse-arma-secreta-pentru-cresterea-vanzarilor-si-dezvoltarea-afacerii\/\" target=\"_blank\">\n\t\t\t\tMatricea de produse: Arma secret\u0103 pentru cre\u0219terea v\u00e2nz\u0103rilor \u0219i dezvoltarea afacerii\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\u00cen lumea afacerilor \u0219i a marketingului exist\u0103 numeroase instrumente pentru analiz\u0103, planificare \u0219i optimizare a produselor. Unul dintre aceste instrumente importante este matricea de produse.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/dev.itmedia.md\/ro\/matricea-de-produse-arma-secreta-pentru-cresterea-vanzarilor-si-dezvoltarea-afacerii\/\" target=\"_blank\">\n\t\t\t\tDETALII \u00bb\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-7369 post type-post status-publish format-standard has-post-thumbnail hentry category-categoria-generala\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/dev.itmedia.md\/ro\/cum-sa-creati-un-magazin-online-de-succes\/\" target=\"_blank\">\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/07\/133948-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/07\/133948-1024x1024.jpg 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/07\/133948-300x300.jpg 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/07\/133948-150x150.jpg 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/07\/133948-768x768.jpg 768w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/07\/133948.jpg 1500w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Categoria general\u0103<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img alt='Victoria Pocitaren\u0441o' src='https:\/\/secure.gravatar.com\/avatar\/6eb994e20d053e54779185f6851c14f1b095333a690aaeb612027924eeaf39df?s=128&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/6eb994e20d053e54779185f6851c14f1b095333a690aaeb612027924eeaf39df?s=256&#038;d=mm&#038;r=g 2x' class='avatar avatar-128 photo' height='128' width='128' \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/dev.itmedia.md\/ro\/cum-sa-creati-un-magazin-online-de-succes\/\" target=\"_blank\">\n\t\t\t\tCum s\u0103 crea\u021bi un magazin online de succes\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Comer\u021bul electronic din Moldova se dezvolt\u0103 rapid. Potrivit statisticilor, cifra de afaceri a comer\u021bului online \u00een Moldova \u00een 2023 a crescut cu peste 30%, comparativ<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/dev.itmedia.md\/ro\/cum-sa-creati-un-magazin-online-de-succes\/\" target=\"_blank\">\n\t\t\t\tDETALII \u00bb\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-6021 post type-post status-publish format-standard has-post-thumbnail hentry category-categoria-generala\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/dev.itmedia.md\/ro\/cum-firma-de-publicitate-itmedia-va-ajuta-sa-iesiti-in-top\/\" target=\"_blank\">\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"427\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/05\/2150063166-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/05\/2150063166-1024x683.jpg 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/05\/2150063166-300x200.jpg 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/05\/2150063166-768x512.jpg 768w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/05\/2150063166.jpg 1500w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Categoria general\u0103<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img alt='Victoria Pocitaren\u0441o' src='https:\/\/secure.gravatar.com\/avatar\/6eb994e20d053e54779185f6851c14f1b095333a690aaeb612027924eeaf39df?s=128&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/6eb994e20d053e54779185f6851c14f1b095333a690aaeb612027924eeaf39df?s=256&#038;d=mm&#038;r=g 2x' class='avatar avatar-128 photo' height='128' width='128' \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/dev.itmedia.md\/ro\/cum-firma-de-publicitate-itmedia-va-ajuta-sa-iesiti-in-top\/\" target=\"_blank\">\n\t\t\t\tServicii de marketing online: Cum firma de publicitate Itmedia v\u0103 ajut\u0103 s\u0103 ie\u0219i\u021bi \u00een top\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Re\u021belele sociale ofer\u0103 companiilor posibilitatea nu doar de a stabili contacte cu publicul lor \u021bint\u0103, ci \u0219i de a-\u0219i promova eficient produsele \u0219i serviciile. Cu<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/dev.itmedia.md\/ro\/cum-firma-de-publicitate-itmedia-va-ajuta-sa-iesiti-in-top\/\" target=\"_blank\">\n\t\t\t\tDETALII \u00bb\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d5e54e9 elementor-widget elementor-widget-html\" data-id=\"4d5e54e9\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"text-align: center;\" class=\"itmnbutton\">\r\n    <a class=\"itmn1\" href=\"https:\/\/dev.itmedia.md\/ro\/blog\/\">\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      Vezi toate \u015ftirile\r\n    <\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7aea050 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7aea050\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9568129\" data-id=\"9568129\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87c30cd elementor-widget elementor-widget-shortcode\" data-id=\"87c30cd\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"7981\" class=\"elementor elementor-7981 elementor-7917\" data-elementor-settings=\"[]\">\n\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-825d6b5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"825d6b5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2f85bd9\" data-id=\"2f85bd9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43590dd elementor-widget elementor-widget-html\" data-id=\"43590dd\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"itm-nstm\">\n<div class=\"itm-main\">\n    <article id=\"furiosa_poster\">\n        <div id=\"furiosa_poster__header\">\n            <h2 id=\"furiosa_poster__header__title\" class=\"furiosa-header-1\" data-title=\"A venit timpul \">A venit timpul <\/h2>\n        <\/div>\n        \n        <div id=\"furiosa_poster__header_2\">\n            <h2 id=\"furiosa_poster__header__title\" class=\"furiosa-header-2\" data-title=\"s\u0103 depune\u0163i o cerere\">s\u0103 depune\u0163i o cerere<\/h2>\n        <\/div>\n        \n <div id=\"furiosa_poster__button\">        \n<div style=\"text-align: center;\" class=\"itmnbutton\">\n    <a class=\"itmn1\" href=\"#popmake-2774\">\n      <span><\/span>\n      <span><\/span>\n      <span><\/span>\n      <span><\/span>\n      Primi\u021bi o consulta\u021bie\n    <\/a>\n<\/div>\n<\/div>\n        \n        <p id=\"furiosa_poster__anya\">Dezvoltarea site-urilor<\/p>\n        <p id=\"furiosa_poster__chris\">Promovarea afacerii<\/p>\n        <p id=\"furiosa_poster__george\">SMM <strong>itmedia.md<\/strong><\/p>\n        <!--<p id=\"furiosa_poster__mad_max_saga\"><span data-title=\"Agentia\"> Agentia<\/span> <span data-title=\"itmedia.md\">itmedia.md<\/span><\/p>-->\n        <img decoding=\"async\" id=\"furiosa_poster__front_image\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/itmedia_manager.png\" alt=\"Furiosa Front image\">\n    <\/article>\n<\/div>\n<!-- partial -->\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Itmedia &#8211; agen\u021bie de publicitate in Chisinau, Moldova Publicitatea contextual\u0103 pe Google\/Yandex Garant\u0103m un flux continuu de clien\u021bi noi \u0219i solicit\u0103ri. Vom cre\u0219te traficul pe [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5333,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2607","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.6 (Yoast SEO v23.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ITMEDIA, Agentia de Publicitate in Chisinau, Moldova - Itmedia<\/title>\n<meta name=\"description\" content=\"Itmedia - agen\u021bie de publicitate. Servicii de Seo, SMM, Elaborare site-uri. Ciclul complet de promovare a afacerii pe internet.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.itmedia.md\/ro\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ITMEDIA, Agentia de Publicitate in Chisinau, Moldova\" \/>\n<meta property=\"og:description\" content=\"Itmedia - agen\u021bie de publicitate. Servicii de Seo, SMM, Elaborare site-uri. Ciclul complet de promovare a afacerii pe internet.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.itmedia.md\/ro\/\" \/>\n<meta property=\"og:site_name\" content=\"Itmedia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/itmedia.md\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-18T10:49:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/01\/computer-desk-information-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/01\/computer-desk-information-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Timp estimat pentru citire\" \/>\n\t<meta name=\"twitter:data1\" content=\"18 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.itmedia.md\/ro\/\",\"url\":\"https:\/\/dev.itmedia.md\/ro\/\",\"name\":\"ITMEDIA, Agentia de Publicitate in Chisinau, Moldova - Itmedia\",\"isPartOf\":{\"@id\":\"https:\/\/dev.itmedia.md\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.itmedia.md\/ro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.itmedia.md\/ro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/01\/computer-desk-information-scaled.jpg\",\"datePublished\":\"2022-12-05T17:08:06+00:00\",\"dateModified\":\"2024-09-18T10:49:02+00:00\",\"description\":\"Itmedia - agen\u021bie de publicitate. Servicii de Seo, SMM, Elaborare site-uri. Ciclul complet de promovare a afacerii pe internet.\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.itmedia.md\/ro\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.itmedia.md\/ro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\/\/dev.itmedia.md\/ro\/#primaryimage\",\"url\":\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/01\/computer-desk-information-scaled.jpg\",\"contentUrl\":\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/01\/computer-desk-information-scaled.jpg\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.itmedia.md\/ro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\/\/dev.itmedia.md\/ro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ITMEDIA, Agentia de Publicitate in Chisinau, Moldova\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.itmedia.md\/#website\",\"url\":\"https:\/\/dev.itmedia.md\/\",\"name\":\"Itmedia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dev.itmedia.md\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.itmedia.md\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.itmedia.md\/#organization\",\"name\":\"itmedia\",\"url\":\"https:\/\/dev.itmedia.md\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\/\/dev.itmedia.md\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/cropped-cropped-itmedia.md-logo.png\",\"contentUrl\":\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/cropped-cropped-itmedia.md-logo.png\",\"width\":254,\"height\":260,\"caption\":\"itmedia\"},\"image\":{\"@id\":\"https:\/\/dev.itmedia.md\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/itmedia.md\",\"https:\/\/www.instagram.com\/itmediate\/\",\"https:\/\/www.linkedin.com\/company\/itmedia-digital-agency\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ITMEDIA, Agentia de Publicitate in Chisinau, Moldova - Itmedia","description":"Itmedia - agen\u021bie de publicitate. Servicii de Seo, SMM, Elaborare site-uri. Ciclul complet de promovare a afacerii pe internet.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.itmedia.md\/ro\/","og_locale":"ro_RO","og_type":"article","og_title":"ITMEDIA, Agentia de Publicitate in Chisinau, Moldova","og_description":"Itmedia - agen\u021bie de publicitate. Servicii de Seo, SMM, Elaborare site-uri. Ciclul complet de promovare a afacerii pe internet.","og_url":"https:\/\/dev.itmedia.md\/ro\/","og_site_name":"Itmedia","article_publisher":"https:\/\/www.facebook.com\/itmedia.md","article_modified_time":"2024-09-18T10:49:02+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/01\/computer-desk-information-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/01\/computer-desk-information-scaled.jpg","twitter_misc":{"Timp estimat pentru citire":"18 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev.itmedia.md\/ro\/","url":"https:\/\/dev.itmedia.md\/ro\/","name":"ITMEDIA, Agentia de Publicitate in Chisinau, Moldova - Itmedia","isPartOf":{"@id":"https:\/\/dev.itmedia.md\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.itmedia.md\/ro\/#primaryimage"},"image":{"@id":"https:\/\/dev.itmedia.md\/ro\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/01\/computer-desk-information-scaled.jpg","datePublished":"2022-12-05T17:08:06+00:00","dateModified":"2024-09-18T10:49:02+00:00","description":"Itmedia - agen\u021bie de publicitate. Servicii de Seo, SMM, Elaborare site-uri. Ciclul complet de promovare a afacerii pe internet.","breadcrumb":{"@id":"https:\/\/dev.itmedia.md\/ro\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.itmedia.md\/ro\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/dev.itmedia.md\/ro\/#primaryimage","url":"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/01\/computer-desk-information-scaled.jpg","contentUrl":"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/01\/computer-desk-information-scaled.jpg","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/dev.itmedia.md\/ro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/dev.itmedia.md\/ro\/"},{"@type":"ListItem","position":2,"name":"ITMEDIA, Agentia de Publicitate in Chisinau, Moldova"}]},{"@type":"WebSite","@id":"https:\/\/dev.itmedia.md\/#website","url":"https:\/\/dev.itmedia.md\/","name":"Itmedia","description":"","publisher":{"@id":"https:\/\/dev.itmedia.md\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.itmedia.md\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Organization","@id":"https:\/\/dev.itmedia.md\/#organization","name":"itmedia","url":"https:\/\/dev.itmedia.md\/","logo":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/dev.itmedia.md\/#\/schema\/logo\/image\/","url":"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/cropped-cropped-itmedia.md-logo.png","contentUrl":"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/cropped-cropped-itmedia.md-logo.png","width":254,"height":260,"caption":"itmedia"},"image":{"@id":"https:\/\/dev.itmedia.md\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/itmedia.md","https:\/\/www.instagram.com\/itmediate\/","https:\/\/www.linkedin.com\/company\/itmedia-digital-agency\/"]}]}},"_links":{"self":[{"href":"https:\/\/dev.itmedia.md\/ro\/wp-json\/wp\/v2\/pages\/2607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.itmedia.md\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.itmedia.md\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.itmedia.md\/ro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.itmedia.md\/ro\/wp-json\/wp\/v2\/comments?post=2607"}],"version-history":[{"count":71,"href":"https:\/\/dev.itmedia.md\/ro\/wp-json\/wp\/v2\/pages\/2607\/revisions"}],"predecessor-version":[{"id":8425,"href":"https:\/\/dev.itmedia.md\/ro\/wp-json\/wp\/v2\/pages\/2607\/revisions\/8425"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.itmedia.md\/ro\/wp-json\/wp\/v2\/media\/5333"}],"wp:attachment":[{"href":"https:\/\/dev.itmedia.md\/ro\/wp-json\/wp\/v2\/media?parent=2607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}