{"id":4843,"date":"2023-08-15T15:07:13","date_gmt":"2023-08-15T12:07:13","guid":{"rendered":"https:\/\/dev.itmedia.md\/?page_id=4843"},"modified":"2024-09-13T10:43:22","modified_gmt":"2024-09-13T07:43:22","slug":"contextual-advertising-google-ads-yandex","status":"publish","type":"page","link":"https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/","title":{"rendered":"Contextual advertising Google Ads \/ Yandex"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4843\" class=\"elementor elementor-4843 elementor-351\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d0b1f06 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d0b1f06\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f002c9b\" data-id=\"f002c9b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-737aa8a elementor-widget elementor-widget-heading\" data-id=\"737aa8a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Contextual advertising Google Ads in Chisinau, Moldova<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-975852d elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"975852d\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9b0269e\" data-id=\"9b0269e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aad4cca elementor-widget elementor-widget-shortcode\" data-id=\"aad4cca\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"8297\" class=\"elementor elementor-8297 elementor-8208\" data-elementor-settings=\"[]\">\n\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-074f4c7 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"074f4c7\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1dff37a\" data-id=\"1dff37a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4be62ea elementor-widget elementor-widget-html\" data-id=\"4be62ea\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"itm-nstm-pro\">\n<div class=\"itm-main-pro\">\n    <article id=\"itm_poster\">\n        <div id=\"itm_poster__header\">\n            <h2 id=\"itm_poster__header__title\" class=\"itm-header-1\" data-title=\"It's time for\">It's time for<\/h2>\n        <\/div>\n        \n        <div id=\"itm_poster__header_2\" class=\"itm_poster__header_2-ro\">\n            <h2 id=\"itm_poster__header__title\" class=\"itm-header-2 itm-header-2-en\" data-title=\"PROMOTION\"> PROMOTION<\/h2>\n        <\/div>\n        \n <div id=\"itm_poster__button\">        \n<div style=\"text-align: center;\" class=\"itmnbutton\">\n    <a class=\"itmn1\" href=\"#popmake-7243\">\n      <span><\/span>\n      <span><\/span>\n      <span><\/span>\n      <span><\/span>\n      Get a consultation\n    <\/a>\n<\/div>\n<\/div>\n        \n        <p id=\"itm_poster__anya\">Website development<\/p>\n        <p id=\"itm_poster__chris\">Business promotion<\/p>\n        <img decoding=\"async\" id=\"itm_poster__front_image\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/itmedia_manager.png\" alt=\"Furiosa Front image\">\n    <\/article>\n<\/div>\n<!-- partial -->\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55aba5d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55aba5d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eab2ff4\" data-id=\"eab2ff4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec7288a mobile-left elementor-widget elementor-widget-heading\" data-id=\"ec7288a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Decide to order contextual advertising setting?<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de929fc elementor-widget elementor-widget-text-editor\" data-id=\"de929fc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>The right decision!<\/strong> Setting up your ad campaign professionally in Google Ads and Yandex, selecting the semantic core and negative keyword list will make it easier to show contextual advertising only to interested consumers, save your budget and multiply your sales.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0394a96 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0394a96\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-aeca198\" data-id=\"aeca198\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41390a3 elementor-widget elementor-widget-heading\" data-id=\"41390a3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Small and medium-sized business issues<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b893a6c elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"b893a6c\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-exclamation\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tCustomers are needed\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a0409d elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"4a0409d\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-exclamation\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tThe necessity to advertise the new production or service\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b232d03 elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"b232d03\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-exclamation\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tFind out if the new product is in demand\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98e3710 elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"98e3710\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-exclamation\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\t The need for profitable advertising\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01c1b22 elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"01c1b22\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-exclamation\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tThe importance of controlling the advertising budget \t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e108949\" data-id=\"e108949\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea1fc62 elementor-widget elementor-widget-heading\" data-id=\"ea1fc62\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">The problem solver - contextual advertising<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19d8b92 elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"19d8b92\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tContinuous flow of customers\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b22be28 elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"b22be28\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tProvide the sales department with requests\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d0dd8f elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"0d0dd8f\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tIncrease website traffic\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-574f178 elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"574f178\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tAbility to sell the product or service quickly\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84732b1 elementor-position-left elementor-vertical-align-middle elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"84732b1\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tFull budget expenditure monitor\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-02e96e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"02e96e1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-43a27ad\" data-id=\"43a27ad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b70acdf elementor-widget elementor-widget-html\" data-id=\"b70acdf\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"text-align: center;\" class=\"itmnbutton\">\r\n    <a class=\"itmn1\" href=\"#popmake-7243\">\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      Get a consultation\r\n    <\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5dab609 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5dab609\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-028c989\" data-id=\"028c989\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de0f490 mobile-left elementor-widget elementor-widget-heading\" data-id=\"de0f490\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Advantages of contextual advertising<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c18d94d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c18d94d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5af70cc\" data-id=\"5af70cc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52382f9 mobile-left elementor-widget elementor-widget-heading\" data-id=\"52382f9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">The announcement will be seen<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42fb9e8 elementor-widget elementor-widget-text-editor\" data-id=\"42fb9e8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>by only those users, who are already interested in your products and services.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5417a66 elementor-widget elementor-widget-image\" data-id=\"5417a66\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_big_crowd_without_paintings_view_from_afar_li_56e35af6-b7c0-4d1f-b8ce-900bd3298d6c-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_big_crowd_without_paintings_view_from_afar_li_56e35af6-b7c0-4d1f-b8ce-900bd3298d6c.png 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_big_crowd_without_paintings_view_from_afar_li_56e35af6-b7c0-4d1f-b8ce-900bd3298d6c-300x300.png 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_big_crowd_without_paintings_view_from_afar_li_56e35af6-b7c0-4d1f-b8ce-900bd3298d6c-150x150.png 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_realistic_big_crowd_without_paintings_view_from_afar_li_56e35af6-b7c0-4d1f-b8ce-900bd3298d6c-768x768.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3bceafd\" data-id=\"3bceafd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0831423 mobile-left elementor-widget elementor-widget-heading\" data-id=\"0831423\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Unlimited list\n<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c87741d elementor-widget elementor-widget-text-editor\" data-id=\"c87741d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>you can use an unlimited list of keywords to promote your advertising.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7578935 elementor-widget elementor-widget-image\" data-id=\"7578935\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_infinity_on_painting_light_gray_background_digital_art_3a6d99d9-064e-49c0-bdb1-f8bc0b68705f-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_infinity_on_painting_light_gray_background_digital_art_3a6d99d9-064e-49c0-bdb1-f8bc0b68705f.png 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_infinity_on_painting_light_gray_background_digital_art_3a6d99d9-064e-49c0-bdb1-f8bc0b68705f-300x300.png 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_infinity_on_painting_light_gray_background_digital_art_3a6d99d9-064e-49c0-bdb1-f8bc0b68705f-150x150.png 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_infinity_on_painting_light_gray_background_digital_art_3a6d99d9-064e-49c0-bdb1-f8bc0b68705f-768x768.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8c1f398 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8c1f398\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-abfbfd4\" data-id=\"abfbfd4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db0271f mobile-left elementor-widget elementor-widget-heading\" data-id=\"db0271f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Quick result<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a57a11a elementor-widget elementor-widget-text-editor\" data-id=\"a57a11a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Results and profit in a short time, without having to wait months. Customers will be coming tomorrow!<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d44e0a8 elementor-widget elementor-widget-image\" data-id=\"d44e0a8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_fast_realitic_businessman_on_painting_light_gray_backgr_d4b923da-233b-4118-b910-e0dc4fe3351b-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_fast_realitic_businessman_on_painting_light_gray_backgr_d4b923da-233b-4118-b910-e0dc4fe3351b.png 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_fast_realitic_businessman_on_painting_light_gray_backgr_d4b923da-233b-4118-b910-e0dc4fe3351b-300x300.png 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_fast_realitic_businessman_on_painting_light_gray_backgr_d4b923da-233b-4118-b910-e0dc4fe3351b-150x150.png 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_fast_realitic_businessman_on_painting_light_gray_backgr_d4b923da-233b-4118-b910-e0dc4fe3351b-768x768.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d4d1ada\" data-id=\"d4d1ada\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e28bb0 mobile-left elementor-widget elementor-widget-heading\" data-id=\"9e28bb0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Gift<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef89263 elementor-position-left elementor-vertical-align-middle zvezdi-kak-mi elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"ef89263\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-gift\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tGift: Detailed analysis of your direct competitors.\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9923fa1 elementor-widget elementor-widget-image\" data-id=\"9923fa1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_businessman_with_magnifying_glass_look_at_crowd_on_pain_dfad6f25-0f4a-4c22-ad6c-201457e2bf5f-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_businessman_with_magnifying_glass_look_at_crowd_on_pain_dfad6f25-0f4a-4c22-ad6c-201457e2bf5f.png 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_businessman_with_magnifying_glass_look_at_crowd_on_pain_dfad6f25-0f4a-4c22-ad6c-201457e2bf5f-300x300.png 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_businessman_with_magnifying_glass_look_at_crowd_on_pain_dfad6f25-0f4a-4c22-ad6c-201457e2bf5f-150x150.png 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/02\/DeniksD_businessman_with_magnifying_glass_look_at_crowd_on_pain_dfad6f25-0f4a-4c22-ad6c-201457e2bf5f-768x768.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e03f068 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e03f068\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e352934\" data-id=\"e352934\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ceb8f19 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"ceb8f19\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"625\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/K-Beauty-Market-is-Booming.-Are-you-taking-note-01-2.webp\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/K-Beauty-Market-is-Booming.-Are-you-taking-note-01-2.webp 850w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/K-Beauty-Market-is-Booming.-Are-you-taking-note-01-2-300x293.webp 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/K-Beauty-Market-is-Booming.-Are-you-taking-note-01-2-768x750.webp 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c56b5fd elementor-invisible\" data-id=\"c56b5fd\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73366af elementor-widget elementor-widget-heading\" data-id=\"73366af\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">We raised sales from 13000 lei to 596000 lei per month<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-113c8d4 elementor-widget elementor-widget-text-editor\" data-id=\"113c8d4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Myskin.md case | Korean cosmetics in Moldova<\/p><p>The result exceeded all our and our customers&#8217; expectations! From the advertising budget of 35000 lei, we closed orders in the amount of 596.646 lei.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33b98aa elementor-widget elementor-widget-html\" data-id=\"33b98aa\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"itmnbutton\">\r\n    <a class=\"itmn\" href=\"#popmake-7243\">\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      I desire the identical\r\n    <\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3acb396 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3acb396\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d0d09be\" data-id=\"d0d09be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6697091 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"6697091\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/bad-in-love-632816_1024x1024@2x-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/bad-in-love-632816_1024x1024@2x-1024x1024.jpg 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/bad-in-love-632816_1024x1024@2x-300x300.jpg 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/bad-in-love-632816_1024x1024@2x-150x150.jpg 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/bad-in-love-632816_1024x1024@2x-768x768.jpg 768w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/bad-in-love-632816_1024x1024@2x.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6097dfa elementor-invisible\" data-id=\"6097dfa\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5c50da elementor-widget elementor-widget-heading\" data-id=\"d5c50da\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Increase sales from 5000\u20ac per month to up to 42000\u20ac<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d094c2c elementor-widget elementor-widget-text-editor\" data-id=\"d094c2c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Case 99paintings.de | Online painting shop in Germany<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2617bc elementor-widget elementor-widget-html\" data-id=\"e2617bc\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"itmnbutton\">\r\n    <a class=\"itmn\" href=\"#popmake-7243\">\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n     I desire the identical\r\n    <\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f32c918 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f32c918\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5e3a3d5\" data-id=\"5e3a3d5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63977b9 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"63977b9\" data-element_type=\"widget\" data-settings=\"{&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;,&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"481\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/kt91vbhyp4-1.webp\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/kt91vbhyp4-1.webp 724w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/02\/kt91vbhyp4-1-300x225.webp 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-db0251c elementor-invisible\" data-id=\"db0251c\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a05d65 elementor-widget elementor-widget-heading\" data-id=\"2a05d65\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">315% increase in ticket sales<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-118ff6e elementor-widget elementor-widget-text-editor\" data-id=\"118ff6e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Passenger transport on various routes<\/p><p>transportpersoane.md<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a1f934 elementor-widget elementor-widget-html\" data-id=\"9a1f934\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"itmnbutton\">\r\n    <a class=\"itmn\" href=\"#popmake-7243\">\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      I desire the identical\r\n    <\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f01716 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f01716\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-465f94d\" data-id=\"465f94d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2d6ff1 elementor-widget elementor-widget-heading\" data-id=\"d2d6ff1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Steps<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2f9d66 mobile-left elementor-widget elementor-widget-heading\" data-id=\"a2f9d66\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">How we work<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d877476 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d877476\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6f218ef\" data-id=\"6f218ef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2994ce elementor-widget elementor-widget-heading\" data-id=\"c2994ce\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Client communication and brief analysis<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3751273 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3751273\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6804153 description elementor-widget elementor-widget-text-editor\" data-id=\"6804153\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Initial communication with the client and completion of the brief will help us understand your goals and tasks.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ea13476\" data-id=\"ea13476\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ba8bd5 elementor-widget elementor-widget-heading\" data-id=\"2ba8bd5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Development of advertising strategy <\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cae7421 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cae7421\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ae7257 description elementor-widget elementor-widget-text-editor\" data-id=\"5ae7257\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>We analyse the completed brief. We develop the advertising strategy and approve it with the client.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-bbc6e45\" data-id=\"bbc6e45\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76046b2 elementor-widget elementor-widget-heading\" data-id=\"76046b2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Closing the agreement and payment<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3fa543 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d3fa543\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b068b62 description elementor-widget elementor-widget-text-editor\" data-id=\"b068b62\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>We send you the agreement for review, negotiate the main points, sign and invoice you for the services rendered.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a5ca111 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a5ca111\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f335b99\" data-id=\"f335b99\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f4ac0f elementor-widget elementor-widget-heading\" data-id=\"2f4ac0f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Work<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-622a737 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"622a737\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8165759 description elementor-widget elementor-widget-text-editor\" data-id=\"8165759\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Setting up Google Ads, Yandex.Direct, Bing Ads, Google Analytics, Yandex.\u041c\u0435\u0442\u0440\u0438\u043a\u0430, Google Tag Manager advertising accounts.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2fbe059\" data-id=\"2fbe059\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94f82c7 elementor-widget elementor-widget-heading\" data-id=\"94f82c7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Monthly report<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c972d2e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c972d2e\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d377e6 description elementor-widget elementor-widget-text-editor\" data-id=\"6d377e6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Every month we provide a report on the services provided and the results of advertising accounts.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ccc4b6d\" data-id=\"ccc4b6d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19d6d42 elementor-widget elementor-widget-html\" data-id=\"19d6d42\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"text-align: center;\" class=\"itmnbutton\">\r\n    <a class=\"itmn1\" href=\"#popmake-7243\">\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      Get a consultation\r\n    <\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-89f79c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"89f79c7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c066b3\" data-id=\"7c066b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b2fa648 elementor-widget elementor-widget-heading\" data-id=\"b2fa648\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Service price<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1c4ee4 elementor-widget elementor-widget-html\" data-id=\"c1c4ee4\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"itm-tsena-one\"><span class=\"itm-tsena-two\">149\u20ac +15%<\/span> from advertising budget<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb5394c elementor-widget elementor-widget-html\" data-id=\"eb5394c\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"text-align: center;\" class=\"itmnbutton\">\r\n    <a class=\"itmn1\" href=\"#popmake-7243\">\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      Order the service\r\n    <\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-de3a6e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"de3a6e8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b9dde4b\" data-id=\"b9dde4b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f4d47d elementor-widget elementor-widget-heading\" data-id=\"8f4d47d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our clients<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76c823b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76c823b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-303ffbf\" data-id=\"303ffbf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3b45d4 elementor-widget elementor-widget-shortcode\" data-id=\"e3b45d4\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"smls-main-logo-outer-118819153 smls-main-logo-wrapper\">\r\n      <div class=\"smls-grid-container-template-2 smls-grid smls-grid-column-4 smls-tablet-column-2 smls-mobile-column-2  smls-hover-type-1 clearfix\r\n     \">\r\n            <div class=\"smls-grid-image-wrap  main-div-1\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/main-logo.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-1\" id=\"contact-div-1\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-2\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/0-02-05-288b00f62c6851e6953f09213fca0cd317a68ea34c43abdfc10e3763ddfcc5a5_88c262e3d51fc679.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-2\" id=\"contact-div-2\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-3\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/alex.jpg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-3\" id=\"contact-div-3\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-4\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/termostar.jpg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-4\" id=\"contact-div-4\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-5\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/Untitled-3-150x150-1.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-5\" id=\"contact-div-5\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-6\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2021\/09\/logo-viniatraian-retina.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-6\" id=\"contact-div-6\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-7\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2021\/09\/Logo-5.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-7\" id=\"contact-div-7\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-8\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/99-logo-BLACK-text-only_180x.webp\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-8\" id=\"contact-div-8\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-9\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/logo-2.svg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-9\" id=\"contact-div-9\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-10\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/logo.jpg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-10\" id=\"contact-div-10\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-11\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/cropped-new-main-logo.018d4590.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-11\" id=\"contact-div-11\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-12\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/romobil.md-logo.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-12\" id=\"contact-div-12\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-13\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/dentlist.jpg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-13\" id=\"contact-div-13\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-14\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/seven.jpg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-14\" id=\"contact-div-14\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-15\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/asmorind.jpg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-15\" id=\"contact-div-15\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-16\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/seven3.jpg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-16\" id=\"contact-div-16\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-17\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2021\/10\/myskin-logo.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-17\" id=\"contact-div-17\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-18\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/logo-4.svg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-18\" id=\"contact-div-18\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-19\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2021\/09\/logo01.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-19\" id=\"contact-div-19\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-20\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/cropped-0-02-05-6b530042474f0f26d9f37d921f2917847412fda32502d3dc17dc3dbe87d637db_5a066005c3752830.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-20\" id=\"contact-div-20\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-21\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/ednateric-trans.svg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-21\" id=\"contact-div-21\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-22\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/calator-md.svg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-22\" id=\"contact-div-22\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-23\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/transerictur.svg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-23\" id=\"contact-div-23\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-24\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2021\/10\/logo-6.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-24\" id=\"contact-div-24\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-25\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/logo_perfectum-module.md_.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-25\" id=\"contact-div-25\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-26\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/lalalaser-logo-1.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-26\" id=\"contact-div-26\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-27\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/laser-epil-studio.jpg\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-27\" id=\"contact-div-27\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n       <div class=\"smls-grid-image-wrap  main-div-28\" >\r\n       <div class=\"smls-grid-pad-container\">\r\n                   <img decoding=\"async\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/holyland-logo-1.png\" alt=\"\">\r\n             <\/div>\r\n<\/div>\r\n<div class=\"popup-contact contact-div-28\" id=\"contact-div-28\">\r\n  <div class=\"smls-overlay-contact-info\">\r\n\r\n    <!--Creates the popup content-->\r\n    \r\n\r\n    <!--Content shown when popup is not displayed-->\r\n\r\n\r\n  <\/div>\r\n<\/div>\r\n          <\/div>\r\n          <style type=\"text\/css\">\r\n            .popup-contact .smls-overlay-contact-info {\r\n              display: none;\r\n            }\r\n            .popup-contact .smls-overlay-contact-info.active {\r\n              display: block;\r\n              position: fixed;\r\n              width: 30%;\r\n              height: 37%;\r\n              background: #000000a6;\r\n              color: #fff;\r\n              left: 30%;\r\n              right: 0;\r\n              top: 30%;\r\n              z-index: 999;\r\n              text-align: center;\r\n            }\r\n            .popup-contact .smls-overlay-contact-info.active .smls-popup-open {\r\n              display: none;\r\n            }\r\n            .popup-contact .smls-overlay-contact-info.active .popup-content {\r\n              visibility: visible;\r\n              \r\n            }\r\n            .popup-content h4, .popup-content h5 {\r\n              color: #FFF;\r\n            }\r\n\r\n\r\n          <\/style>\r\n            <\/div>\r\n  <style>\n    .smls-main-logo-outer-118819153.smls-main-logo-wrapper {\n        width: 100%;\n        margin:0 auto;\n    }\n    .smls-main-logo-outer-118819153 .smls-grid-container-template-1 .smls-grid-each-item:before,\n    .smls-main-logo-outer-118819153 .smls-grid-container-template-1 .smls-grid-image-wrap:before,\n    .smls-main-logo-outer-118819153 .smls-grid-container-template-2 .smls-grid-each-item:before,\n    .smls-main-logo-outer-118819153 .smls-grid-container-template-2 .smls-grid-image-wrap:before {\n\n        border-left: 1px solid #e9e9e9;\n    }\n    .smls-main-logo-outer-118819153 .smls-grid-container-template-1 .smls-grid-each-item:after,\n    .smls-main-logo-outer-118819153 .smls-grid-container-template-1 .smls-grid-image-wrap:after,\n    .smls-main-logo-outer-118819153 .smls-grid-container-template-2 .smls-grid-each-item:after,\n    .smls-main-logo-outer-118819153 .smls-grid-container-template-2 .smls-grid-image-wrap:after {\n        border-bottom: 1px solid #e9e9e9;\n    }\n    .smls-main-logo-outer-118819153 .smls-grid-container-template-2 {\n        border: 1px solid #e9e9e9;\n    }\n\n    .smls-main-logo-outer-118819153 .smls-carousel-pager-template-2.owl-theme .owl-dots .owl-dot span:before\n    {\n        background-color:  #0d98dc;\n\n    }\n    .smls-main-logo-outer-118819153 .smls-carousel-pager-template-2.owl-theme .owl-dots .owl-dot span {\n        background:  #7c7c7c;\n    }\n\n    .smls-main-logo-outer-118819153 .smls-carousel-arrow-type-1.owl-theme .owl-controls .owl-nav [class*=owl-]:hover {\n        background-color: rgba(71, 71, 71, 0.7);\n    }\n    .smls-main-logo-outer-118819153 .smls-carousel-arrow-type-1.owl-theme .owl-controls .owl-nav [class*=owl-] {\n        background-color: #474747;\n    }\n    .smls-main-logo-outer-118819153 .smls-carousel-arrow-type-2.owl-theme .owl-controls .owl-nav [class*=owl-] {\n        background-color:  #474747;\n    }\n    .smls-main-logo-outer-118819153 .smls-carousel-arrow-type-2.owl-theme .owl-controls .owl-nav [class*=owl-]:hover {\n        background-color: rgba(71, 71, 71, 0.7);\n    }\n    .smls-main-logo-outer-118819153 .smls-carousel-arrow-type-3.owl-theme .owl-controls .owl-nav [class*=owl-] {\n        border: 2px solid #474747;\n\n    }\n    .smls-main-logo-outer-118819153 .smls-carousel-arrow-type-3.owl-theme .owl-controls .owl-nav [class*=owl-]:before {\n        background-color: rgba(71, 71, 71, 0.7);\n    }\n    .smls-main-logo-outer-118819153 .smls-carousel-arrow-type-3.owl-theme .owl-controls .owl-nav [class*=owl-]:hover {\n        border-color: rgba(71, 71, 71, 0.7);\n    }\n    .smls-main-logo-outer-118819153 .smls-carousel-arrow-type-4.owl-theme .owl-controls .owl-nav [class*=owl-] {\n        border: 2px solid #474747;\n        color: #474747;\n    }\n    .smls-main-logo-outer-118819153 .smls-carousel-arrow-type-4.owl-carousel .owl-controls .owl-nav [class*=owl-]:hover {\n        background-color: rgba(71, 71, 71, 0.7);\n        color: #333333;\n    }\n    .smls-main-logo-outer-118819153 .smls-carousel-arrow-type-5.owl-theme .owl-controls .owl-nav [class*=owl-] {\n        background-color:  #474747;\n\n    }\n\n    .smls-main-logo-outer-118819153 .smls-carousel-template-2.owl-carousel .smls-carousel-four-items {\n        border: 1px solid  #eee;\n    }\n\n<\/style><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a884f01 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a884f01\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0354760\" data-id=\"0354760\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-79b329a elementor-widget elementor-widget-heading\" data-id=\"79b329a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">and many others<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fbc3a99 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fbc3a99\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e759c37\" data-id=\"e759c37\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31818ff elementor-widget elementor-widget-html\" data-id=\"31818ff\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"text-align: center;\" class=\"itmnbutton\">\r\n    <a class=\"itmn1\" href=\"#popmake-7243\">\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n     Make your request\r\n    <\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1705a6ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1705a6ef\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66b57f00\" data-id=\"66b57f00\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-229cfe25 elementor-widget elementor-widget-heading\" data-id=\"229cfe25\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The latest news<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-277922ee elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-posts--show-avatar elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"277922ee\" data-element_type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-8609 post type-post status-publish format-standard has-post-thumbnail hentry category-general-category\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/dev.itmedia.md\/en\/product-matrix-a-secret-weapon-for-boosting-sales-and-business-growth\/\" target=\"_blank\">\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/10\/itmedia-produktovaya-matricza-sekretnoe-oruzhie-dlya-uvelicheniya-prodazh-i-rosta-biznesa.webp\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/10\/itmedia-produktovaya-matricza-sekretnoe-oruzhie-dlya-uvelicheniya-prodazh-i-rosta-biznesa.webp 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/10\/itmedia-produktovaya-matricza-sekretnoe-oruzhie-dlya-uvelicheniya-prodazh-i-rosta-biznesa-300x300.webp 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/10\/itmedia-produktovaya-matricza-sekretnoe-oruzhie-dlya-uvelicheniya-prodazh-i-rosta-biznesa-150x150.webp 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/10\/itmedia-produktovaya-matricza-sekretnoe-oruzhie-dlya-uvelicheniya-prodazh-i-rosta-biznesa-768x768.webp 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">General category<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img alt='\u0410\u0440\u0442\u0443\u0440' src='https:\/\/secure.gravatar.com\/avatar\/39aac8628cc4f633ab4887737e18f8cde23187b7958281a447f7e27d0524ef7b?s=128&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/39aac8628cc4f633ab4887737e18f8cde23187b7958281a447f7e27d0524ef7b?s=256&#038;d=mm&#038;r=g 2x' class='avatar avatar-128 photo' height='128' width='128' \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/dev.itmedia.md\/en\/product-matrix-a-secret-weapon-for-boosting-sales-and-business-growth\/\" target=\"_blank\">\n\t\t\t\tProduct Matrix: A Secret Weapon for Boosting Sales and Business Growth\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>In the world of business and marketing, there are numerous tools for analyzing, planning, and optimizing products. One such crucial tool is the product matrix.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/dev.itmedia.md\/en\/product-matrix-a-secret-weapon-for-boosting-sales-and-business-growth\/\" target=\"_blank\">\n\t\t\t\tDETAILS \u00bb\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4959 post type-post status-publish format-standard has-post-thumbnail hentry category-general-category\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/dev.itmedia.md\/en\/evolutia-sloganului-si-a-logoului-pana-in-prezent\/\" target=\"_blank\">\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/08\/evolution-on-brands.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/08\/evolution-on-brands.png 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/08\/evolution-on-brands-300x300.png 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/08\/evolution-on-brands-150x150.png 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/08\/evolution-on-brands-768x768.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">General category<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img alt='admin' src='https:\/\/secure.gravatar.com\/avatar\/7e5d5a9b48dad37961f66f0424407492afe54dadc1c19dc9c7d19cf40ee4c44d?s=128&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/7e5d5a9b48dad37961f66f0424407492afe54dadc1c19dc9c7d19cf40ee4c44d?s=256&#038;d=mm&#038;r=g 2x' class='avatar avatar-128 photo' height='128' width='128' \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/dev.itmedia.md\/en\/evolutia-sloganului-si-a-logoului-pana-in-prezent\/\" target=\"_blank\">\n\t\t\t\tEvolution of the slogan and logo to date\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Slogans have evolved. &#8220;Have a break, have a Kit Kat&#8221; became a refuge in a hectic world, and Apple&#8217;s &#8220;Think Different&#8221; encouraged innovation and creativity.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/dev.itmedia.md\/en\/evolutia-sloganului-si-a-logoului-pana-in-prezent\/\" target=\"_blank\">\n\t\t\t\tDETAILS \u00bb\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-4952 post type-post status-publish format-standard has-post-thumbnail hentry category-general-category\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/dev.itmedia.md\/en\/ethics-in-publicity-and-responsible-communication\/\" target=\"_blank\">\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/08\/ethics.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/08\/ethics.png 1024w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/08\/ethics-300x300.png 300w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/08\/ethics-150x150.png 150w, https:\/\/dev.itmedia.md\/wp-content\/uploads\/2023\/08\/ethics-768x768.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">General category<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t<img alt='admin' src='https:\/\/secure.gravatar.com\/avatar\/7e5d5a9b48dad37961f66f0424407492afe54dadc1c19dc9c7d19cf40ee4c44d?s=128&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/7e5d5a9b48dad37961f66f0424407492afe54dadc1c19dc9c7d19cf40ee4c44d?s=256&#038;d=mm&#038;r=g 2x' class='avatar avatar-128 photo' height='128' width='128' \/>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/dev.itmedia.md\/en\/ethics-in-publicity-and-responsible-communication\/\" target=\"_blank\">\n\t\t\t\tEthics in Publicity and Responsible Communication\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p> Avoiding stereotypes and messages that might offend certain groups is essential to build a positive image. Transparency in communication is also crucial. <\/p>\n\t\t<\/div>\n\t\t\t\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/dev.itmedia.md\/en\/ethics-in-publicity-and-responsible-communication\/\" target=\"_blank\">\n\t\t\t\tDETAILS \u00bb\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c42db77 elementor-widget elementor-widget-html\" data-id=\"c42db77\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"text-align: center;\" class=\"itmnbutton\">\r\n    <a class=\"itmn1\" href=\"https:\/\/dev.itmedia.md\/en\/itmedia-blog-your-solid-agency-for-tech-insights\/\">\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      <span><\/span>\r\n      See all news\r\n    <\/a>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28f3886 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28f3886\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f9dfc80\" data-id=\"f9dfc80\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-49e0f27 elementor-widget elementor-widget-shortcode\" data-id=\"49e0f27\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"8038\" class=\"elementor elementor-8038 elementor-7917\" data-elementor-settings=\"[]\">\n\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-825d6b5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"825d6b5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2f85bd9\" data-id=\"2f85bd9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43590dd elementor-widget elementor-widget-html\" data-id=\"43590dd\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"itm-nstm\">\n<div class=\"itm-main\">\n    <article id=\"furiosa_poster\">\n        <div id=\"furiosa_poster__header\">\n            <h2 id=\"furiosa_poster__header__title\" class=\"furiosa-header-1\" data-title=\"It's time to \">It's time to <\/h2>\n        <\/div>\n        \n        <div id=\"furiosa_poster__header_2\">\n            <h2 id=\"furiosa_poster__header__title\" class=\"furiosa-header-2\" data-title=\"submit a request\">submit a request<\/h2>\n        <\/div>\n        \n <div id=\"furiosa_poster__button\">        \n<div style=\"text-align: center;\" class=\"itmnbutton\">\n    <a class=\"itmn1\" href=\"#popmake-7243\">\n      <span><\/span>\n      <span><\/span>\n      <span><\/span>\n      <span><\/span>\n      Get a consultation\n    <\/a>\n<\/div>\n<\/div>\n        \n        <p id=\"furiosa_poster__anya\">Website development<\/p>\n        <p id=\"furiosa_poster__chris\">Business promotion<\/p>\n        <p id=\"furiosa_poster__george\">SMM <strong>itmedia.md<\/strong><\/p>\n        <!--<p id=\"furiosa_poster__mad_max_saga\"><span data-title=\"Agentia\"> Agentia<\/span> <span data-title=\"itmedia.md\">itmedia.md<\/span><\/p>-->\n        <img decoding=\"async\" id=\"furiosa_poster__front_image\" src=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/itmedia_manager.png\" alt=\"Furiosa Front image\">\n    <\/article>\n<\/div>\n<!-- partial -->\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Contextual advertising Google Ads in Chisinau, Moldova Decide to order contextual advertising setting? The right decision! Setting up your ad campaign professionally in Google Ads [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5458,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4843","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.6 (Yoast SEO v23.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contextual (Search) Advertising in Google Ads - Itmedia<\/title>\n<meta name=\"description\" content=\"Setting up your ad campaign professionally in Google Ads, selecting the semantic core and keyword list will save your budget and multiply sales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contextual advertising Google Ads \/ Yandex\" \/>\n<meta property=\"og:description\" content=\"Setting up your ad campaign professionally in Google Ads, selecting the semantic core and keyword list will save your budget and multiply sales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/\" \/>\n<meta property=\"og:site_name\" content=\"Itmedia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/itmedia.md\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-13T07:43:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/01\/arafed-laptop-computer-with-magnifying-glass-mouse-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/01\/arafed-laptop-computer-with-magnifying-glass-mouse-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/\",\"url\":\"https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/\",\"name\":\"Contextual (Search) Advertising in Google Ads - Itmedia\",\"isPartOf\":{\"@id\":\"https:\/\/dev.itmedia.md\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/01\/arafed-laptop-computer-with-magnifying-glass-mouse-scaled.jpg\",\"datePublished\":\"2023-08-15T12:07:13+00:00\",\"dateModified\":\"2024-09-13T07:43:22+00:00\",\"description\":\"Setting up your ad campaign professionally in Google Ads, selecting the semantic core and keyword list will save your budget and multiply sales.\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/#primaryimage\",\"url\":\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/01\/arafed-laptop-computer-with-magnifying-glass-mouse-scaled.jpg\",\"contentUrl\":\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/01\/arafed-laptop-computer-with-magnifying-glass-mouse-scaled.jpg\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\/\/dev.itmedia.md\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contextual advertising Google Ads \/ Yandex\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.itmedia.md\/#website\",\"url\":\"https:\/\/dev.itmedia.md\/\",\"name\":\"Itmedia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dev.itmedia.md\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.itmedia.md\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dev.itmedia.md\/#organization\",\"name\":\"itmedia\",\"url\":\"https:\/\/dev.itmedia.md\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/dev.itmedia.md\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/cropped-cropped-itmedia.md-logo.png\",\"contentUrl\":\"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/cropped-cropped-itmedia.md-logo.png\",\"width\":254,\"height\":260,\"caption\":\"itmedia\"},\"image\":{\"@id\":\"https:\/\/dev.itmedia.md\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/itmedia.md\",\"https:\/\/www.instagram.com\/itmediate\/\",\"https:\/\/www.linkedin.com\/company\/itmedia-digital-agency\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Contextual (Search) Advertising in Google Ads - Itmedia","description":"Setting up your ad campaign professionally in Google Ads, selecting the semantic core and keyword list will save your budget and multiply sales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/","og_locale":"en_US","og_type":"article","og_title":"Contextual advertising Google Ads \/ Yandex","og_description":"Setting up your ad campaign professionally in Google Ads, selecting the semantic core and keyword list will save your budget and multiply sales.","og_url":"https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/","og_site_name":"Itmedia","article_publisher":"https:\/\/www.facebook.com\/itmedia.md","article_modified_time":"2024-09-13T07:43:22+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/01\/arafed-laptop-computer-with-magnifying-glass-mouse-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/01\/arafed-laptop-computer-with-magnifying-glass-mouse-scaled.jpg","twitter_misc":{"Est. reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/","url":"https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/","name":"Contextual (Search) Advertising in Google Ads - Itmedia","isPartOf":{"@id":"https:\/\/dev.itmedia.md\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/#primaryimage"},"image":{"@id":"https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/#primaryimage"},"thumbnailUrl":"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/01\/arafed-laptop-computer-with-magnifying-glass-mouse-scaled.jpg","datePublished":"2023-08-15T12:07:13+00:00","dateModified":"2024-09-13T07:43:22+00:00","description":"Setting up your ad campaign professionally in Google Ads, selecting the semantic core and keyword list will save your budget and multiply sales.","breadcrumb":{"@id":"https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/#primaryimage","url":"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/01\/arafed-laptop-computer-with-magnifying-glass-mouse-scaled.jpg","contentUrl":"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2024\/01\/arafed-laptop-computer-with-magnifying-glass-mouse-scaled.jpg","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/dev.itmedia.md\/en\/contextual-advertising-google-ads-yandex\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/dev.itmedia.md\/en\/"},{"@type":"ListItem","position":2,"name":"Contextual advertising Google Ads \/ Yandex"}]},{"@type":"WebSite","@id":"https:\/\/dev.itmedia.md\/#website","url":"https:\/\/dev.itmedia.md\/","name":"Itmedia","description":"","publisher":{"@id":"https:\/\/dev.itmedia.md\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.itmedia.md\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dev.itmedia.md\/#organization","name":"itmedia","url":"https:\/\/dev.itmedia.md\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dev.itmedia.md\/#\/schema\/logo\/image\/","url":"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/cropped-cropped-itmedia.md-logo.png","contentUrl":"https:\/\/dev.itmedia.md\/wp-content\/uploads\/2022\/05\/cropped-cropped-itmedia.md-logo.png","width":254,"height":260,"caption":"itmedia"},"image":{"@id":"https:\/\/dev.itmedia.md\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/itmedia.md","https:\/\/www.instagram.com\/itmediate\/","https:\/\/www.linkedin.com\/company\/itmedia-digital-agency\/"]}]}},"_links":{"self":[{"href":"https:\/\/dev.itmedia.md\/en\/wp-json\/wp\/v2\/pages\/4843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.itmedia.md\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.itmedia.md\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.itmedia.md\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.itmedia.md\/en\/wp-json\/wp\/v2\/comments?post=4843"}],"version-history":[{"count":36,"href":"https:\/\/dev.itmedia.md\/en\/wp-json\/wp\/v2\/pages\/4843\/revisions"}],"predecessor-version":[{"id":8306,"href":"https:\/\/dev.itmedia.md\/en\/wp-json\/wp\/v2\/pages\/4843\/revisions\/8306"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.itmedia.md\/en\/wp-json\/wp\/v2\/media\/5458"}],"wp:attachment":[{"href":"https:\/\/dev.itmedia.md\/en\/wp-json\/wp\/v2\/media?parent=4843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}